{"id":19281,"date":"2015-04-18T16:30:46","date_gmt":"2015-04-18T15:30:46","guid":{"rendered":"http:\/\/www.moda.es\/blog\/?p=19281"},"modified":"2020-04-27T16:59:49","modified_gmt":"2020-04-27T15:59:49","slug":"alexander-wang-y-diane-von-furstenberg-entre-los-mas-influyentes-segun-time","status":"publish","type":"post","link":"http:\/\/www.moda.es\/blog\/alexander-wang-y-diane-von-furstenberg-entre-los-mas-influyentes-segun-time\/","title":{"rendered":"Alexander Wang y Diane von Furstenberg entre los m\u00e1s influyentes seg\u00fan Time"},"content":{"rendered":"<p>La etiqueta de los <strong>\u00abm\u00e1s influyentes\u00bb es<\/strong> muy codiciada en la moda. Cada a\u00f1o, diversas publicaciones e instituciones hacen la suya, pero pocas tienen tanta relevancia como la de la lista mundial de <strong>Las 100 personas m\u00e1s influyentes<\/strong> de la revista <strong>Time.<\/strong><\/p>\n<p>El a\u00f1o pasado la directora creativa de <strong>C\u00e9line, Phoebe Philo<\/strong> y la fundadora de <strong>Net-A-Porter.com, Natalie Massenet<\/strong>, se convirtieron en las \u00fanicas dos figuras de la moda\u00a0 nombradas en la lista. Este a\u00f1o el turno es de <strong>Alexander Wang y Diane von Furstenberg.<\/strong><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.moda.es\/blog\/wp-content\/uploads\/2015\/04\/dvf-wang.jpg\"><img data-attachment-id=\"19282\" data-permalink=\"http:\/\/www.moda.es\/blog\/alexander-wang-y-diane-von-furstenberg-entre-los-mas-influyentes-segun-time\/dvf-wang\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.moda.es\/blog\/wp-content\/uploads\/2015\/04\/dvf-wang.jpg?fit=650%2C733\" data-orig-size=\"650,733\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"dvf-wang\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.moda.es\/blog\/wp-content\/uploads\/2015\/04\/dvf-wang.jpg?fit=266%2C300\" data-large-file=\"https:\/\/i0.wp.com\/www.moda.es\/blog\/wp-content\/uploads\/2015\/04\/dvf-wang.jpg?fit=640%2C722\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-19282\" alt=\"dvf-wang\" src=\"https:\/\/i0.wp.com\/www.moda.es\/blog\/wp-content\/uploads\/2015\/04\/dvf-wang.jpg?resize=266%2C300\" width=\"266\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/www.moda.es\/blog\/wp-content\/uploads\/2015\/04\/dvf-wang.jpg?resize=266%2C300 266w, https:\/\/i0.wp.com\/www.moda.es\/blog\/wp-content\/uploads\/2015\/04\/dvf-wang.jpg?resize=420%2C473 420w, https:\/\/i0.wp.com\/www.moda.es\/blog\/wp-content\/uploads\/2015\/04\/dvf-wang.jpg?w=650 650w\" sizes=\"(max-width: 266px) 100vw, 266px\" data-recalc-dims=\"1\" \/><\/a><\/p>\n<p>La entrada de Wang se debe entre otras cosas a las alabanzas de<strong> Karlie Kloss,<\/strong> quien le llama el \u00abni\u00f1o m\u00e1s <em>cool<\/em> de la moda\u00bb. \u00abEl truco de su \u00e9xito no es s\u00f3lo talento, dedicaci\u00f3n y una \u00e9tica de trabajo, sino su habilidad \u00fanica para hacer <strong>alta moda en todas partes\u00bb,<\/strong> escribe Kloss. \u00abEl n\u00facleo de su imperio se basa en c\u00f3mo ama su trabajo y disfruta de su industria \u00ab.<\/p>\n<p>El\u00a0 dise\u00f1ador de Nueva York a sus 31 a\u00f1os\u00a0 ha disfrutado de un \u00e9xito notable en los \u00faltimos 12 meses con su colaboraci\u00f3n con <strong>H&amp;M<\/strong>, sus dos marcas del mismo nombre, Alexander Wang y\u00a0 la l\u00ednea m\u00e1s asequible<strong> T by Alexander Wang<\/strong>, y su trabajo como director creativo de <strong>Balenciaga<\/strong>.<\/p>\n<p>La dise\u00f1adora y fil\u00e1ntropa von Furstenberg es elogiada por la actriz <strong>Jessica Alba<\/strong>, quien comenta: \u00abSu constante inspiraci\u00f3n nos recuerda que nada se ve mejor en una mujer es la claridad, el coraje y la convicci\u00f3n\u00bb.<\/p>\n<p>\u00abLa moda es una herramienta para la fantas\u00eda, pero Diane von Furstenberg la utiliz\u00f3 para mostrarnos que podemos transformarla en nuestra realidad\u00bb, a\u00f1ade. \u00abLa vida de Diane es ciertamente fant\u00e1stico: portadas de revistas y retratos de Warhol. Pero no olvidemos: Ella hizo su propio destino, y ha sido con orgullo, una mujer trabajadora y madre. Debe ser por eso que su ic\u00f3nico \u00abwrap dress\u00bb est\u00e1 hecho para la vida moderna. Est\u00e1 construido para <strong>la velocidad, la sofisticaci\u00f3n y la simplicidad celebrando adem\u00e1s la feminidad<\/strong>\u00ab.<\/p>\n<p>Los dos dise\u00f1adores se unen en la lista a los cantantes <strong>Kanye West y Taylor Swift<\/strong>, la joven activista <strong>Malala Yousafzia<\/strong>, la bailarina de ballet <strong>Misty Copeland<\/strong> y la estrella <strong>Kim Kardashian.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>\u00a9Fashion Telegraph                             <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La etiqueta de los \u00abm\u00e1s influyentes\u00bb es muy codiciada en la moda. Cada a\u00f1o, diversas publicaciones e instituciones hacen la suya, pero pocas tienen tanta relevancia como la de la lista mundial de Las 100 personas m\u00e1s influyentes de la revista Time. El a\u00f1o pasado la directora creativa de C\u00e9line, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":19282,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[3,11,12,18],"tags":[108,179,433,466,1137,1214,1120],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.moda.es\/blog\/wp-content\/uploads\/2015\/04\/dvf-wang.jpg?fit=650%2C733","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4tJCC-50Z","jetpack-related-posts":[{"id":22677,"url":"http:\/\/www.moda.es\/blog\/ya-tenemos-nominados-para-los-fashion-awards\/","url_meta":{"origin":19281,"position":0},"title":"Ya tenemos nominados para los Fashion Awards","date":"octubre 25, 2017","format":false,"excerpt":"Los nominados para los Fashion Awards 2017\u00a0en asociaci\u00f3n con Swarovski han sido revelados. LA ceremonia tendr\u00e1 lugar el 4 de diciembre en el Royal Albert Hall de Londres y parece que estar\u00e1 re\u00f1ido porque todos son grandes talentos. \"Estos dise\u00f1adores y marcas fueron elegidos entre cientos de nombres internacionales y\u2026","rel":"","context":"En \u00abActualidad\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.moda.es\/blog\/wp-content\/uploads\/2017\/10\/Captura-de-pantalla-2017-10-25-a-las-23.00.32.png?fit=312%2C461&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":17510,"url":"http:\/\/www.moda.es\/blog\/la-cara-mas-solidaria-de-la-moda\/","url_meta":{"origin":19281,"position":1},"title":"La cara m\u00e1s solidaria de la moda","date":"abril 19, 2014","format":false,"excerpt":"Victoria Beckham es s\u00f3lo uno de los nombres de dise\u00f1adores que crear\u00e1n colecciones de\u00a0piezas\u00a0 madre - hijo en exclusiva para la organizaci\u00f3n ben\u00e9fica Born Free. La brit\u00e1nica ha sorprendido en Twitter con la imagen de la modelo Sasha Pivovarova y su hija Mia vestidas a juego con vestidos dise\u00f1ados por\u2026","rel":"","context":"En \u00abActualidad\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.moda.es\/blog\/wp-content\/uploads\/2014\/04\/Born-Free-3.jpg?fit=650%2C975&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":15612,"url":"http:\/\/www.moda.es\/blog\/daria-werbowy-para-balenciaga\/","url_meta":{"origin":19281,"position":2},"title":"Daria Werbowy para Balenciaga","date":"enero 15, 2014","format":false,"excerpt":"Es como si estuvi\u00e9ramos siendo invitados al resurgimiento de las m\u00edticas que estaban dejando paso a las nuevas generaciones. Las modelos que siempre nos han gustado siguen pisando fuerte, y si no que se lo digan a Daria Werbowy. A\u00fan esperando las im\u00e1genes de la canadiense como estrella invitada de\u2026","rel":"","context":"En \u00abCampa\u00f1as\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.moda.es\/blog\/wp-content\/uploads\/2014\/01\/Balenciaga-11.jpg?fit=500%2C333&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":171,"url":"http:\/\/www.moda.es\/blog\/la-hora-del-te-perdon-de-los-premios\/","url_meta":{"origin":19281,"position":3},"title":"La hora del t\u00e9&#8230; perd\u00f3n, de los premios","date":"diciembre 10, 2010","format":false,"excerpt":"La moda brit\u00e1nica ha celebrado el pasado martes d\u00eda 7\u00a0la gala de sus premios, The British Fashion Awards, que reconoce a las personas (inglesas) m\u00e1s influyentes en la moda de hoy, al tiempo que\u00a0celebran la fama y el\u00a0empuje de la moda brit\u00e1nica. Nombres tan familiares como el de Phoebe Philo\u2026","rel":"","context":"En \u00abAlfombra Roja\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.moda.es\/blog\/wp-content\/uploads\/2010\/12\/alexa-chung.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":22649,"url":"http:\/\/www.moda.es\/blog\/phoebe-philo-a-punto-de-dejar-celine\/","url_meta":{"origin":19281,"position":4},"title":"Phoebe Philo, a punto de dejar Celine","date":"octubre 17, 2017","format":false,"excerpt":"Si bien no es la primera vez que se especula sobre la posible salida de la Directora Creativa de la marca, ahora parece que podr\u00eda ser una realidad y Phoebe Philo est\u00e1 a punto de abandonar su puesto en LVMH. De acuerdo con fuentes an\u00f3nimas citadas por Business of Fashion,\u2026","rel":"","context":"En \u00abDestacados\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.moda.es\/blog\/wp-content\/uploads\/2017\/10\/Captura-de-pantalla-2017-10-17-a-las-23.53.19.png?fit=496%2C745&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":17757,"url":"http:\/\/www.moda.es\/blog\/cannes-se-viste-de-rojo\/","url_meta":{"origin":19281,"position":5},"title":"Cannes se viste de rojo","date":"mayo 24, 2014","format":false,"excerpt":"S\u00f3lo Carine Roitfeld, la Gala amfAR y la magn\u00edfica causa, la lucha contra el SIDA, pod\u00edan conseguir reunir a algunas de las mujeres m\u00e1s bellas del mundo para desfilar en una gran noche. El Hotel du Cap-Eden-Roc fue testigo de los desfiles, no s\u00f3lo de las grandes de la pasarela\u2026","rel":"","context":"En \u00abActualidad\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.moda.es\/blog\/wp-content\/uploads\/2014\/05\/Cannes-8.jpg?fit=650%2C487&resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"http:\/\/www.moda.es\/blog\/wp-json\/wp\/v2\/posts\/19281"}],"collection":[{"href":"http:\/\/www.moda.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.moda.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.moda.es\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.moda.es\/blog\/wp-json\/wp\/v2\/comments?post=19281"}],"version-history":[{"count":7,"href":"http:\/\/www.moda.es\/blog\/wp-json\/wp\/v2\/posts\/19281\/revisions"}],"predecessor-version":[{"id":36151,"href":"http:\/\/www.moda.es\/blog\/wp-json\/wp\/v2\/posts\/19281\/revisions\/36151"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.moda.es\/blog\/wp-json\/wp\/v2\/media\/19282"}],"wp:attachment":[{"href":"http:\/\/www.moda.es\/blog\/wp-json\/wp\/v2\/media?parent=19281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.moda.es\/blog\/wp-json\/wp\/v2\/categories?post=19281"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.moda.es\/blog\/wp-json\/wp\/v2\/tags?post=19281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}