{"id":10929,"date":"2013-02-19T00:58:41","date_gmt":"2013-02-18T22:58:41","guid":{"rendered":"http:\/\/www.moda.es\/blog\/wp-content\/uploads\/2013\/02\/Ana-Fernandez-de-Santos-Costura.jpg"},"modified":"2013-02-19T00:58:41","modified_gmt":"2013-02-18T22:58:41","slug":"ana-fernandez-de-santos-costura","status":"inherit","type":"attachment","link":"http:\/\/www.moda.es\/blog\/ana-fernandez-de-santos-costura\/","title":{"rendered":"Ana Fernandez de Santos Costura"},"author":3,"comment_status":"open","ping_status":"open","template":"","meta":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a4tJCC-2Qh","description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/i0.wp.com\/www.moda.es\/blog\/wp-content\/uploads\/2013\/02\/Ana-Fernandez-de-Santos-Costura.jpg'><img width=\"200\" height=\"300\" src=\"https:\/\/i0.wp.com\/www.moda.es\/blog\/wp-content\/uploads\/2013\/02\/Ana-Fernandez-de-Santos-Costura.jpg?fit=200%2C300\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/www.moda.es\/blog\/wp-content\/uploads\/2013\/02\/Ana-Fernandez-de-Santos-Costura.jpg?w=800 800w, https:\/\/i0.wp.com\/www.moda.es\/blog\/wp-content\/uploads\/2013\/02\/Ana-Fernandez-de-Santos-Costura.jpg?resize=200%2C300 200w, https:\/\/i0.wp.com\/www.moda.es\/blog\/wp-content\/uploads\/2013\/02\/Ana-Fernandez-de-Santos-Costura.jpg?resize=682%2C1024 682w\" sizes=\"(max-width: 200px) 100vw, 200px\" data-attachment-id=\"10929\" data-permalink=\"http:\/\/www.moda.es\/blog\/ana-fernandez-de-santos-costura\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.moda.es\/blog\/wp-content\/uploads\/2013\/02\/Ana-Fernandez-de-Santos-Costura.jpg?fit=800%2C1200\" data-orig-size=\"800,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Ana Fernandez de Santos Costura\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Ana Fernandez de Santos Costura&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/i0.wp.com\/www.moda.es\/blog\/wp-content\/uploads\/2013\/02\/Ana-Fernandez-de-Santos-Costura.jpg?fit=200%2C300\" data-large-file=\"https:\/\/i0.wp.com\/www.moda.es\/blog\/wp-content\/uploads\/2013\/02\/Ana-Fernandez-de-Santos-Costura.jpg?fit=640%2C961\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Ana Fernandez de Santos Costura<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":1200,"file":"2013\/02\/Ana-Fernandez-de-Santos-Costura.jpg","sizes":{"thumbnail":{"file":"Ana-Fernandez-de-Santos-Costura-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.moda.es\/blog\/wp-content\/uploads\/2013\/02\/Ana-Fernandez-de-Santos-Costura.jpg?resize=150%2C150"},"medium":{"file":"Ana-Fernandez-de-Santos-Costura-200x300.jpg","width":200,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.moda.es\/blog\/wp-content\/uploads\/2013\/02\/Ana-Fernandez-de-Santos-Costura.jpg?fit=200%2C300"},"large":{"file":"Ana-Fernandez-de-Santos-Costura-682x1024.jpg","width":682,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.moda.es\/blog\/wp-content\/uploads\/2013\/02\/Ana-Fernandez-de-Santos-Costura.jpg?fit=640%2C961"},"post-thumbnail":{"file":"Ana-Fernandez-de-Santos-Costura-672x372.jpg","width":672,"height":372,"mime_type":"image\/jpeg","source_url":"http:\/\/www.moda.es\/blog\/wp-content\/uploads\/2013\/02\/Ana-Fernandez-de-Santos-Costura-672x372.jpg"},"twentyfourteen-full-width":{"file":"Ana-Fernandez-de-Santos-Costura-800x576.jpg","width":800,"height":576,"mime_type":"image\/jpeg","source_url":"http:\/\/www.moda.es\/blog\/wp-content\/uploads\/2013\/02\/Ana-Fernandez-de-Santos-Costura-800x576.jpg"},"full":{"file":"Ana-Fernandez-de-Santos-Costura.jpg?fit=800%2C1200","width":800,"height":1200,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.moda.es\/blog\/wp-content\/uploads\/2013\/02\/Ana-Fernandez-de-Santos-Costura.jpg?fit=800%2C1200"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":null,"source_url":"http:\/\/www.moda.es\/blog\/wp-content\/uploads\/2013\/02\/Ana-Fernandez-de-Santos-Costura.jpg","_links":{"self":[{"href":"http:\/\/www.moda.es\/blog\/wp-json\/wp\/v2\/media\/10929"}],"collection":[{"href":"http:\/\/www.moda.es\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/www.moda.es\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/www.moda.es\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.moda.es\/blog\/wp-json\/wp\/v2\/comments?post=10929"}]}}